{"id":446,"count":1,"description":"","link":"https:\/\/www.sucre.net\/en\/tag\/proyectos-de-construccion\/","name":"Proyectos de construcci\u00f3n","slug":"proyectos-de-construccion","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Proyectos de construcci\u00f3n en Ciudad de Panam\u00e1<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.sucre.net\/en\/tag\/proyectos-de-construccion\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Proyectos de construcci\u00f3n en Ciudad de Panam\u00e1\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.sucre.net\/en\/tag\/proyectos-de-construccion\/\" \/>\n<meta property=\"og:site_name\" content=\"Sucre Arias Reyes\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.sucre.net\/wp-content\/uploads\/2024\/06\/sucre-video-bkgn-hero-ok.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/www.sucre.net\\\/tag\\\/proyectos-de-construccion\\\/\",\"url\":\"https:\\\/\\\/www.sucre.net\\\/tag\\\/proyectos-de-construccion\\\/\",\"name\":\"Proyectos de construcci\u00f3n en Ciudad de Panam\u00e1\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.sucre.net\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.sucre.net\\\/tag\\\/proyectos-de-construccion\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.sucre.net\\\/tag\\\/proyectos-de-construccion\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.sucre.net\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Proyectos de construcci\u00f3n\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.sucre.net\\\/#website\",\"url\":\"https:\\\/\\\/www.sucre.net\\\/\",\"name\":\"Sucre Arias Reyes\",\"description\":\"Firma de abogados en Panam\u00e1\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.sucre.net\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.sucre.net\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.sucre.net\\\/#organization\",\"name\":\"Sucre Arias Reyes\",\"url\":\"https:\\\/\\\/www.sucre.net\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.sucre.net\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.sucre.net\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/logo-sucre.png\",\"contentUrl\":\"https:\\\/\\\/www.sucre.net\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/logo-sucre.png\",\"width\":800,\"height\":426,\"caption\":\"Sucre Arias Reyes\"},\"image\":{\"@id\":\"https:\\\/\\\/www.sucre.net\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/SucreAriasReyes\\\/\",\"https:\\\/\\\/www.instagram.com\\\/sarpanama\\\/\",\"https:\\\/\\\/pa.linkedin.com\\\/company\\\/sucre-arias-reyes\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Proyectos de construcci\u00f3n en Ciudad de Panam\u00e1","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.sucre.net\/en\/tag\/proyectos-de-construccion\/","og_locale":"en_US","og_type":"article","og_title":"Proyectos de construcci\u00f3n en Ciudad de Panam\u00e1","og_url":"https:\/\/www.sucre.net\/en\/tag\/proyectos-de-construccion\/","og_site_name":"Sucre Arias Reyes","og_image":[{"width":1920,"height":1080,"url":"https:\/\/www.sucre.net\/wp-content\/uploads\/2024\/06\/sucre-video-bkgn-hero-ok.webp","type":"image\/webp"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.sucre.net\/tag\/proyectos-de-construccion\/","url":"https:\/\/www.sucre.net\/tag\/proyectos-de-construccion\/","name":"Proyectos de construcci\u00f3n en Ciudad de Panam\u00e1","isPartOf":{"@id":"https:\/\/www.sucre.net\/#website"},"breadcrumb":{"@id":"https:\/\/www.sucre.net\/tag\/proyectos-de-construccion\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/www.sucre.net\/tag\/proyectos-de-construccion\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.sucre.net\/"},{"@type":"ListItem","position":2,"name":"Proyectos de construcci\u00f3n"}]},{"@type":"WebSite","@id":"https:\/\/www.sucre.net\/#website","url":"https:\/\/www.sucre.net\/","name":"Sucre Arias Reyes","description":"Law firm in Panama","publisher":{"@id":"https:\/\/www.sucre.net\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.sucre.net\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.sucre.net\/#organization","name":"Sucre Arias Reyes","url":"https:\/\/www.sucre.net\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.sucre.net\/#\/schema\/logo\/image\/","url":"https:\/\/www.sucre.net\/wp-content\/uploads\/2024\/02\/logo-sucre.png","contentUrl":"https:\/\/www.sucre.net\/wp-content\/uploads\/2024\/02\/logo-sucre.png","width":800,"height":426,"caption":"Sucre Arias Reyes"},"image":{"@id":"https:\/\/www.sucre.net\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/SucreAriasReyes\/","https:\/\/www.instagram.com\/sarpanama\/","https:\/\/pa.linkedin.com\/company\/sucre-arias-reyes"]}]}},"_links":{"self":[{"href":"https:\/\/www.sucre.net\/en\/wp-json\/wp\/v2\/tags\/446","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.sucre.net\/en\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.sucre.net\/en\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.sucre.net\/en\/wp-json\/wp\/v2\/posts?tags=446"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}